{"id":10099,"date":"2025-01-17T12:19:42","date_gmt":"2025-01-17T20:19:42","guid":{"rendered":"https:drivesaversdatarecovery.com\/\/?p=10099"},"modified":"2026-03-05T05:31:20","modified_gmt":"2026-03-05T13:31:20","slug":"fire-damaged-devices-recoverable-or-not","status":"publish","type":"post","link":"https:\/\/drivesaversdatarecovery.com\/it-it\/blog\/fire-damaged-devices-recoverable-or-not\/","title":{"rendered":"Dispositivi danneggiati dal fuoco: recuperabili o no?"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><div class=\"vc_section wpex-relative\"><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1692829928220 vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_column-gap-10 vc_row-o-equal-height vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative no-bottom-margins tablet-fullwidth-columns\"><div class=\"wpb_column vc_column_container vc_col-sm-3 vc_hidden-md vc_hidden-sm vc_hidden-xs\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module\"><div class=\"vcex-image-inner wpex-relative wpex-w-100\"><img width=\"2160\" height=\"2160\" src=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43.jpg\" class=\"vcex-image-img wpex-align-middle wpex-w-100 wpex-aspect-1-1 wpex-object-cover\" alt=\"A severely damaged smartphone with a shattered screen and burnt components on a red background. There is a circular logo with text in the bottom right corner.\" decoding=\"async\" srcset=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43.jpg 2160w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-300x300.jpg 300w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-1024x1024.jpg 1024w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-150x150.jpg 150w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-768x768.jpg 768w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-1536x1536.jpg 1536w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-2048x2048.jpg 2048w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2024\/12\/43-12x12.jpg 12w\" sizes=\"(max-width: 2160px) 100vw, 2160px\" \/><\/div><\/figure><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-9\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"color:#222222;\" class=\"wpb_text_column has-custom-color wpex-child-inherit-color wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Gli ingegneri di DriveSavers hanno acquisito grande esperienza dopo gli incendi del 2017 nel nord della California, una serie di quindici roghi iniziati nella tarda serata di domenica 8 ottobre. Hanno devastato le contee di Sonoma, Napa e Lake, distruggendo case e interi quartieri. Sappiamo in prima persona che tipo di danni da incendio possiamo aspettarci quando arriveranno dispositivi provenienti dai recenti incendi nel sud della California.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 15px\"><span class=\"vc_empty_space_inner\"><\/span><\/div>\n\t<div style=\"color:#222222;\" class=\"wpb_text_column has-custom-color wpex-child-inherit-color wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>DriveSavers ha storicamente avuto molto successo nel recupero di dati da dispositivi danneggiati dal fuoco; tuttavia, molti dispositivi provenienti da incendi di vasta portata sono risultati irrecuperabili. Continua a leggere per scoprire alcuni segnali che indicano se i dati possono essere recuperati.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h4 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h4\"><span class=\"vcex-heading-inner wpex-inline-block\">Indice<\/span><\/h4>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<ol>\n<li><a href=\"#differance\">La differenza tra incendi isolati di strutture e incendi boschivi<\/a><\/li>\n<li><a href=\"#causes\">Come il fuoco danneggia un computer<\/a><\/li>\n<li><a href=\"#recoverable\">Capire se i tuoi dati possono essere recuperati<\/a><\/li>\n<\/ol>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1692827636460 vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-top vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module wpex-text-center\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"1200\" height=\"627\" src=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/Updated-1700-Degree-Inferno.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/Updated-1700-Degree-Inferno.jpg 1200w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/Updated-1700-Degree-Inferno-300x157.jpg 300w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/Updated-1700-Degree-Inferno-1024x535.jpg 1024w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/Updated-1700-Degree-Inferno-768x401.jpg 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/><\/div><\/figure><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_custom_1692827636460 vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div id=\"differance\" class=\"vc_row wpb_row vc_row-fluid vc_custom_1692984429408 vc_rtl-columns-reverse vc_row-o-content-middle vc_row-flex wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h2\"><span class=\"vcex-heading-inner wpex-inline-block\">La differenza tra incendi isolati di strutture e incendi boschivi<\/span><\/h2><div class=\"vc_empty_space\"   style=\"height: 32px\"><span class=\"vc_empty_space_inner\"><\/span><\/div><div class=\"vc_row wpb_row vc_inner vc_row-fluid wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"860\" height=\"2000\" src=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres.png\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres.png 860w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres-129x300.png 129w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres-440x1024.png 440w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres-768x1786.png 768w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres-660x1536.png 660w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/what_not_to_do_with_fire_08242023_highres-881x2048.png 881w\" sizes=\"(max-width: 860px) 100vw, 860px\" \/><\/div><\/figure><\/div><\/div><\/div><div class=\"wpb_column vc_column_container vc_col-sm-6\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div style=\"color:#222222;\" class=\"wpb_text_column has-custom-color wpex-child-inherit-color wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Questi incendi boschivi estesi e duraturi hanno caratteristiche molto diverse rispetto a un normale incendio isolato di edificio.<\/p>\n<ul>\n<li>Temperatura<\/li>\n<li>Durata<\/li>\n<li>Contaminanti aggiuntivi<\/li>\n<\/ul>\n\n\t\t<\/div>\n\t<\/div>\n\n\t<div style=\"color:#222222;\" class=\"wpb_text_column has-custom-color wpex-child-inherit-color wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Temperatura<\/h3>\n<p>Gli incendi domestici normalmente raggiungono i 1.000 \u00b0F, mentre gli incendi boschivi come quelli del sud della California possono arrivare fino a 1.800 \u00b0F, o persino 3.000 \u00b0F nel tempo. Questo intervallo di temperature rende gli incendi boschivi molto pi\u00f9 distruttivi rispetto a quelli domestici.<\/p>\n<p>Un altro fattore \u00e8 il calore diretto rispetto al calore irradiato. Nel caso di un incendio isolato in un edificio, i vigili del fuoco intervengono solitamente entro dieci minuti dalla segnalazione e riescono spesso a contenere le fiamme in una sola stanza prima che si propaghino. Gli oggetti direttamente nelle fiamme subiscono temperature pi\u00f9 elevate e danni maggiori, mentre quelli al di fuori del fuoco generalmente subiscono meno danni.<\/p>\n<h3>Durata<\/h3>\n<p>Mentre alcuni incendi in edifici possono durare diverse ore, la maggior parte delle abitazioni unifamiliari viene spenta in meno di un\u2019ora. Al contrario, la maggior parte delle case e delle attivit\u00e0 coinvolte in questi vasti incendi boschivi ha bruciato ininterrottamente per dodici ore o pi\u00f9, fino a esaurire il combustibile per le fiamme. Il tempo durante il quale un dispositivo di archiviazione dati \u00e8 esposto al fuoco \u00e8 un fattore determinante.<\/p>\n<p>Uno dei motivi per cui la durata di un incendio \u00e8 importante \u00e8 che pi\u00f9 a lungo brucia, pi\u00f9 il fuoco diventa caldo. A seconda dei materiali che alimentano le fiamme, la temperatura all\u2019interno pu\u00f2 superare i 2.200 \u00b0F in appena quattro ore. In otto ore, questa temperatura pu\u00f2 salire di altri 100 \u00b0F, arrivando a 2.300 \u00b0F. Gli incendi pi\u00f9 intensi possono raggiungere fino a 5.500 \u00b0F! Tuttavia, si tratta di casi estremi e rari. La maggior parte degli incendi di lunga durata, come quelli di Los Angeles, Palisades ed Eaton, si ferma intorno ai 3.000 \u00b0F.<\/p>\n<p>Inoltre, quando una casa viene colpita da un incendio boschivo che ha gi\u00e0 raggiunto temperature estreme prima di arrivare all\u2019edificio, l\u2019intera struttura e i suoi contenuti possono incendiarsi istantaneamente. Ci\u00f2 \u00e8 particolarmente probabile in presenza di materiali combustibili.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div>\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<h3>Contaminanti aggiuntivi<\/h3>\n<p>Le fiamme e il calore non sono gli unici elementi di un incendio che possono danneggiare un computer e il suo dispositivo di archiviazione dati. L\u2019acqua utilizzata per spegnere l\u2019incendio, i detriti, la fuliggine e le sostanze chimiche come i ritardanti di fiamma possono anch\u2019essi causare danni aggiuntivi.<\/p>\n<p>Water and flame retardant, used by firefighters on isolated single-family home fires and other comparatively smaller incidents may be absent from devices recovered from a wildfire. This is because, once the wildfire is contained, houses toward the middle of the fire will simply burn out, or run out of fuel and extinguish on their own without aid from water or flame retardant, before firefighters are physically able to get to it.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div id=\"causes\" class=\"vc_row wpb_row vc_row-fluid wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h2\"><span class=\"vcex-heading-inner wpex-inline-block\">Come il fuoco danneggia un computer<\/span><\/h2><div class=\"vc_row wpb_row vc_inner vc_row-fluid wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Nessun dispositivo viene distrutto istantaneamente e completamente da un incendio, sia esso un tragico incendio domestico o un devastante incendio boschivo. Ecco alcune conseguenze comuni.<\/p>\n<h3>Parti in plastica<\/h3>\n<p>In praticamente ogni incendio, i componenti in plastica si sciolgono. Un PC odierno pu\u00f2 contenere dal 17\u202f% al 40\u202f% di plastica. Questo include i tasti della tastiera, parti del case esterno, l\u2019isolamento interno e persino alcuni condensatori e circuiti elettronici. Che siano direttamente contattati dalla fiamma o colpiti indirettamente dal calore del fuoco, le plastiche iniziano generalmente a sciogliersi ben prima che la temperatura raggiunga i 500\u202f\u00b0F.<\/p>\n<h3>Guarnizioni in gomma<\/h3>\n<p>I dischi rigidi (HDD) e alcuni dischi a stato solido (SSD) hanno un involucro metallico che protegge i componenti di memorizzazione dei dati. Questi involucri sono generalmente sigillati con una guarnizione in gomma di tipo industriale. Questo tipo di gomma inizia solitamente a sciogliersi intorno ai 620\u202f\u00b0F.<\/p>\n<p>Ci\u00f2 non significa necessariamente che i componenti interni siano compromessi a tale temperatura. Se la guarnizione in gomma resta al suo posto, anche se si \u00e8 ammorbidita, i componenti interni restano protetti da detriti esterni, ecc.<\/p>\n<p>D\u2019altra parte, una volta che questa guarnizione in gomma di un disco rigido \u00e8 compromessa e si notano dei fori, anche minuscoli, nella tenuta, \u00e8 molto probabile che i dati memorizzati sul dispositivo non siano pi\u00f9 recuperabili. Ci\u00f2 \u00e8 dovuto al fatto che qualsiasi fuliggine, fumo o altro contaminante, una volta all\u2019interno dell\u2019unit\u00e0, provocher\u00e0 ulteriori danni ai piatti che contengono i veri e propri uno e zero che costituiscono i dati.<\/p>\n<p>Il recupero dati da un SSD \u00e8 diverso rispetto a un disco rigido, poich\u00e9 i chip che compongono un SSD non sono influenzati dalle particelle. Se il case di un SSD \u00e8 danneggiato, ci sono comunque buone possibilit\u00e0 di recuperare i dati.<\/p>\n<h3>Piatti<\/h3>\n<p>All\u2019interno di un disco rigido si trovano dei piatti che somigliano a specchi rotondi montati su un perno. Questi dischi memorizzano tutti i dati del computer. A seconda del produttore e del modello, i piatti possono essere realizzati in alluminio, vetro, ceramica, cobalto o in una combinazione di due o pi\u00f9 di questi materiali. I piatti tendono a essere piuttosto resistenti al calore e spesso sopportano temperature elevate prima di iniziare a deformarsi, formare bolle o sciogliersi.<\/p>\n<h3>Metallo<\/h3>\n<p>I computer sono composti principalmente da metallo. Il case esterno, i chip di controllo, i chip di memoria (in un SSD), i connettori, i circuiti e diversi altri componenti sono generalmente realizzati con vari tipi di metallo:<\/p>\n<ul>\n<li>Esterno: solitamente in alluminio<\/li>\n<li>Chip di memoria o NAND: solitamente in silicio<\/li>\n<li>Circuiti: solitamente in silicio<\/li>\n<li>Altri componenti possono essere composti da piombo, rame, oro o stagno.<\/li>\n<\/ul>\n<p>Il silicio \u00e8 particolarmente resistente al calore e pu\u00f2 sopportare temperature fino a 1.370 \u00b0C. Tuttavia, \u00e8 importante notare che, anche a temperature pi\u00f9 basse, la resistenza del silicio e della maggior parte dei metalli si riduce con l\u2019esposizione prolungata al calore o alle fiamme. Ogni minuto pu\u00f2 fare la differenza per salvare il dispositivo di archiviazione o i dati in esso contenuti.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><figure class=\"vcex-image vcex-module\"><div class=\"vcex-image-inner wpex-relative wpex-inline-block\"><img width=\"2000\" height=\"1541\" src=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-scaled.jpg\" class=\"vcex-image-img wpex-align-middle\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-scaled.jpg 2000w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-300x231.jpg 300w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-1024x789.jpg 1024w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-768x592.jpg 768w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-1536x1183.jpg 1536w, https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/the-mistery-of-fire-damage_08232023_highres-2048x1577.jpg 2048w\" sizes=\"(max-width: 2000px) 100vw, 2000px\" \/><\/div><\/figure><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><div id=\"recoverable\" class=\"vc_row wpb_row vc_row-fluid wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><h2 class=\"vcex-heading vcex-heading-plain vcex-module wpex-heading wpex-text-2xl wpex-h2\"><span class=\"vcex-heading-inner wpex-inline-block\">Capire se i tuoi dati possono essere recuperati<\/span><\/h2><div class=\"vc_row wpb_row vc_inner vc_row-fluid wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t<div class=\"wpb_text_column wpb_content_element\" >\n\t\t<div class=\"wpb_wrapper\">\n\t\t\t<p>Ecco alcuni elementi da considerare per capire se i dati possono essere recuperati da un dispositivo danneggiato dal fuoco.<\/p>\n<h3>C\u2019era presenza d\u2019acqua?<\/h3>\n<p>Molte case e uffici sono dotati di sistemi antincendio attivati dal calore. Anche se l\u2019edificio \u00e8 andato completamente distrutto, un sistema di irrigazione funzionante potrebbe aver raffreddato il computer e impedito la perdita permanente dei dati.<\/p>\n<p>Quando i vigili del fuoco intervengono su un edificio in fiamme, usano migliaia di litri d\u2019acqua per spegnere l\u2019incendio. Anche in assenza di un sistema di irrigazione, l\u2019acqua utilizzata pu\u00f2 facilmente danneggiare i computer e altri dispositivi.<\/p>\n<p>Invece di essere danneggiato dal calore o dal fuoco, un dispositivo in una di queste due situazioni presenter\u00e0 quasi certamente danni causati dall\u2019acqua. In tal caso, portalo subito da DriveSavers per recuperare i dati prima che la corrosione si diffonda.<\/p>\n<h3>Il computer \u00e8 bruciato o fuso?<\/h3>\n<p>Se il computer \u00e8 fuso ma non ci sono segni evidenti di contatto diretto con le fiamme, come bruciature o carbonizzazione, \u00e8 molto probabile che i dati siano recuperabili. E anche in presenza di segni di bruciatura, non perdere subito la speranza.<\/p>\n<h3>Ci sono degli adesivi?<\/h3>\n<p>Se ci sono ancora etichette del produttore sul disco rigido o su altri componenti interni del computer, \u00e8 un ottimo segno: il calore non \u00e8 stato abbastanza intenso da causare una perdita permanente dei dati e questi potrebbero essere recuperabili.<\/p>\n<h3>Quanto \u00e8 intatto il case del disco rigido?<\/h3>\n<p>Anche se l\u2019esterno del computer \u00e8 fuso o bruciato, ci\u00f2 che conta davvero \u00e8 lo stato del disco rigido.<\/p>\n<p>Se riesci a individuare il disco rigido all\u2019interno del computer e risulta ancora integro, senza compromissioni alla guarnizione in gomma che tiene unito il case, ci sono buone probabilit\u00e0 di riuscire a recuperare i dati.<\/p>\n<p>Molti dei computer che abbiamo ricevuto dopo gli incendi nel nord della California avevano dischi rigidi fusi o ridotti in cenere. Se non resta nulla del disco rigido, purtroppo non \u00e8 possibile recuperare alcun dato.<\/p>\n<h3>Riesci a identificare i chip?<\/h3>\n<p>Se riesci a trovare dei chip che sembrano integri, \u00e8 probabile che anche il disco del computer sia ancora funzionante e che i dati siano recuperabili. Questo vale per i chip sulla scheda madre, ma soprattutto se i chip di un SSD o di un altro tipo di memoria flash appaiono completi e poco danneggiati.<\/p>\n<h3>Non sei sicuro che i tuoi dati possano essere recuperati? Chiama DriveSavers.<\/h3>\n<p>I nostri consulenti per il recupero dati ti aiuteranno a capire se il tuo dispositivo di archiviazione pu\u00f2 essere recuperato. Ti forniremo un\u2019etichetta di spedizione gratuita in modo che DriveSavers possa effettuare una valutazione gratuita del dispositivo e comunicarti le probabilit\u00e0 di successo.<\/p>\n<p class=\"translation-block\">Chiama il <strong>1 (800) 440-1904<\/strong>. I consulenti per il recupero dati di DriveSavers sono disponibili 24 ore su 24, 7 giorni su 7, e possono avviare subito il processo di recupero.<\/p>\n\n\t\t<\/div>\n\t<\/div>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><div class=\"vc_row wpb_row vc_row-fluid vc_row-o-content-middle vc_row-flex wpex-vc-full-width-row wpex-vc-full-width-row--centered wpex-relative\"><div class=\"wpb_column vc_column_container vc_col-sm-12\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"vc_separator wpb_content_element vc_separator_align_center vc_sep_width_100 vc_sep_dashed vc_sep_border_width_3 vc_sep_pos_align_center vc_separator_no_text vc_sep_color_white wpb_content_element  wpb_content_element\" ><span class=\"vc_sep_holder vc_sep_holder_l\"><span class=\"vc_sep_line\"><\/span><\/span><span class=\"vc_sep_holder vc_sep_holder_r\"><span class=\"vc_sep_line\"><\/span><\/span>\n<\/div><\/div><\/div><\/div><\/div><\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Nessun dispositivo viene distrutto istantaneamente e completamente da un incendio, sia esso un tragico incendio domestico o un devastante incendio boschivo. Ecco alcune conseguenze comuni.<\/p>","protected":false},"author":25,"featured_media":66435,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"om_disable_all_campaigns":false,"inline_featured_image":false,"footnotes":""},"categories":[264],"tags":[59,11464],"post_series":[],"class_list":["post-10099","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-data-recovery","tag-elements","entry","has-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v28.2 (Yoast SEO v28.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Fire-Damaged Devices: Recoverable or Not?<\/title>\n<meta name=\"description\" content=\"No device is instantly and entirely destroyed by a fire, whether it is a tragic house fire or a catastrophic wildfire. Here are some common consequences.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/drivesaversdatarecovery.com\/it-it\/blog\/fire-damaged-devices-recoverable-or-not\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fire-Damaged Devices: Recoverable or Not?\" \/>\n<meta property=\"og:description\" content=\"No device is instantly and entirely destroyed by a fire, whether it is a tragic house fire or a catastrophic wildfire. Here are some common consequences.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/drivesaversdatarecovery.com\/it-it\/blog\/fire-damaged-devices-recoverable-or-not\/\" \/>\n<meta property=\"og:site_name\" content=\"DriveSavers Data Recovery Services\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DriveSavers\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-17T20:19:42+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-05T13:31:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/fires-temp.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"627\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Mike Cobb\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@drivesavers\" \/>\n<meta name=\"twitter:site\" content=\"@drivesavers\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mike Cobb\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"TechArticle\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/\"},\"author\":{\"name\":\"Mike Cobb\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#\\\/schema\\\/person\\\/71a038c3b180b1f2df821d2b015b8ee6\"},\"headline\":\"Fire-Damaged Devices: Recoverable or Not?\",\"datePublished\":\"2025-01-17T20:19:42+00:00\",\"dateModified\":\"2026-03-05T13:31:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/\"},\"wordCount\":1964,\"publisher\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fires-temp.png\",\"keywords\":[\"data recovery\",\"elements\"],\"articleSection\":[\"Blog\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/\",\"url\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/\",\"name\":\"Fire-Damaged Devices: Recoverable or Not?\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fires-temp.png\",\"datePublished\":\"2025-01-17T20:19:42+00:00\",\"dateModified\":\"2026-03-05T13:31:20+00:00\",\"description\":\"No device is instantly and entirely destroyed by a fire, whether it is a tragic house fire or a catastrophic wildfire. Here are some common consequences.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#primaryimage\",\"url\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fires-temp.png\",\"contentUrl\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/wp-content\\\/uploads\\\/2023\\\/08\\\/fires-temp.png\",\"width\":1200,\"height\":627},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/blog\\\/fire-damaged-devices-recoverable-or-not\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"DriveSavers\",\"item\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fire-Damaged Devices: Recoverable or Not?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#website\",\"url\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/\",\"name\":\"DriveSavers Data Recovery Services\",\"description\":\"The Worldwide Leader in Data Recovery\",\"publisher\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#organization\",\"name\":\"DriveSavers Data Recovery\",\"url\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Logo-01.png\",\"contentUrl\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Logo-01.png\",\"width\":1092,\"height\":1087,\"caption\":\"DriveSavers Data Recovery\"},\"image\":{\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/DriveSavers\",\"https:\\\/\\\/x.com\\\/drivesavers\",\"https:\\\/\\\/www.instagram.com\\\/drivesavers\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/drivesavers-data-recovery\\\/\",\"https:\\\/\\\/www.pinterest.com\\\/drivesavers\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UCBlynLMdFWQgid-Gwm0zJ1A\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/DriveSavers\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/#\\\/schema\\\/person\\\/71a038c3b180b1f2df821d2b015b8ee6\",\"name\":\"Mike Cobb\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c8d091f4e2a84113483109e20b50ac463596024c46f59a7ebcbfa90985755e?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c8d091f4e2a84113483109e20b50ac463596024c46f59a7ebcbfa90985755e?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/45c8d091f4e2a84113483109e20b50ac463596024c46f59a7ebcbfa90985755e?s=96&d=blank&r=g\",\"caption\":\"Mike Cobb\"},\"description\":\"Mike Cobb, Director of Engineering and CISO As Director of Engineering, Mike Cobb manages the day-to-day operations of the Engineering Department, including the physical and logical recoveries of rotational media, SSDs, smart devices and flash media. He also oversees the R&amp;D efforts for past, present, and future storage technologies. Mike encourages growth and ensures that each of the departments and their engineers continues to gain knowledge in their field. Each DriveSavers engineer has been trained to ensure the successful and complete recovery of data is their top priority. As Chief Information Security Officer (CISO), Mike oversees cybersecurity at DriveSavers, including maintaining and updating security certifications such as SOC 2 Type II compliance, coordinating company security policy, and employee cybersecurity education. Mike joined DriveSavers in 1994 and has a B.S. degree in Computer Science from the University of California, Riverside.\",\"sameAs\":[\"http:\\\/\\\/\\\/\"],\"url\":\"https:\\\/\\\/drivesaversdatarecovery.com\\\/it-it\\\/author\\\/mikecobb\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Dispositivi danneggiati dal fuoco: recuperabili o no?","description":"Nessun dispositivo viene distrutto istantaneamente e completamente da un incendio, sia esso un tragico incendio domestico o un devastante incendio boschivo. Ecco alcune conseguenze comuni.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/drivesaversdatarecovery.com\/it-it\/blog\/fire-damaged-devices-recoverable-or-not\/","og_locale":"it_IT","og_type":"article","og_title":"Fire-Damaged Devices: Recoverable or Not?","og_description":"No device is instantly and entirely destroyed by a fire, whether it is a tragic house fire or a catastrophic wildfire. Here are some common consequences.","og_url":"https:\/\/drivesaversdatarecovery.com\/it-it\/blog\/fire-damaged-devices-recoverable-or-not\/","og_site_name":"DriveSavers Data Recovery Services","article_publisher":"https:\/\/www.facebook.com\/DriveSavers","article_published_time":"2025-01-17T20:19:42+00:00","article_modified_time":"2026-03-05T13:31:20+00:00","og_image":[{"width":1200,"height":627,"url":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/fires-temp.png","type":"image\/png"}],"author":"Mike Cobb","twitter_card":"summary_large_image","twitter_creator":"@drivesavers","twitter_site":"@drivesavers","twitter_misc":{"Scritto da":"Mike Cobb","Tempo di lettura stimato":"8 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"TechArticle","@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#article","isPartOf":{"@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/"},"author":{"name":"Mike Cobb","@id":"https:\/\/drivesaversdatarecovery.com\/#\/schema\/person\/71a038c3b180b1f2df821d2b015b8ee6"},"headline":"Fire-Damaged Devices: Recoverable or Not?","datePublished":"2025-01-17T20:19:42+00:00","dateModified":"2026-03-05T13:31:20+00:00","mainEntityOfPage":{"@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/"},"wordCount":1964,"publisher":{"@id":"https:\/\/drivesaversdatarecovery.com\/#organization"},"image":{"@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#primaryimage"},"thumbnailUrl":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/fires-temp.png","keywords":["data recovery","elements"],"articleSection":["Blog"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/","url":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/","name":"Dispositivi danneggiati dal fuoco: recuperabili o no?","isPartOf":{"@id":"https:\/\/drivesaversdatarecovery.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#primaryimage"},"image":{"@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#primaryimage"},"thumbnailUrl":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/fires-temp.png","datePublished":"2025-01-17T20:19:42+00:00","dateModified":"2026-03-05T13:31:20+00:00","description":"Nessun dispositivo viene distrutto istantaneamente e completamente da un incendio, sia esso un tragico incendio domestico o un devastante incendio boschivo. Ecco alcune conseguenze comuni.","breadcrumb":{"@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#primaryimage","url":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/fires-temp.png","contentUrl":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2023\/08\/fires-temp.png","width":1200,"height":627},{"@type":"BreadcrumbList","@id":"https:\/\/drivesaversdatarecovery.com\/blog\/fire-damaged-devices-recoverable-or-not\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"DriveSavers","item":"https:\/\/drivesaversdatarecovery.com\/"},{"@type":"ListItem","position":2,"name":"Fire-Damaged Devices: Recoverable or Not?"}]},{"@type":"WebSite","@id":"https:\/\/drivesaversdatarecovery.com\/#website","url":"https:\/\/drivesaversdatarecovery.com\/","name":"Servizi di recupero dati DriveSavers","description":"The Worldwide Leader in Data Recovery","publisher":{"@id":"https:\/\/drivesaversdatarecovery.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/drivesaversdatarecovery.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/drivesaversdatarecovery.com\/#organization","name":"DriveSavers Italia","url":"https:\/\/drivesaversdatarecovery.com\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/drivesaversdatarecovery.com\/#\/schema\/logo\/image\/","url":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2021\/08\/Logo-01.png","contentUrl":"https:\/\/drivesaversdatarecovery.com\/wp-content\/uploads\/2021\/08\/Logo-01.png","width":1092,"height":1087,"caption":"DriveSavers Data Recovery"},"image":{"@id":"https:\/\/drivesaversdatarecovery.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DriveSavers","https:\/\/x.com\/drivesavers","https:\/\/www.instagram.com\/drivesavers\/","https:\/\/www.linkedin.com\/company\/drivesavers-data-recovery\/","https:\/\/www.pinterest.com\/drivesavers\/","https:\/\/www.youtube.com\/channel\/UCBlynLMdFWQgid-Gwm0zJ1A","https:\/\/en.wikipedia.org\/wiki\/DriveSavers"]},{"@type":"Person","@id":"https:\/\/drivesaversdatarecovery.com\/#\/schema\/person\/71a038c3b180b1f2df821d2b015b8ee6","name":"Mike Cobb","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/45c8d091f4e2a84113483109e20b50ac463596024c46f59a7ebcbfa90985755e?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/45c8d091f4e2a84113483109e20b50ac463596024c46f59a7ebcbfa90985755e?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/45c8d091f4e2a84113483109e20b50ac463596024c46f59a7ebcbfa90985755e?s=96&d=blank&r=g","caption":"Mike Cobb"},"description":"Mike Cobb, Director of Engineering and CISO As Director of Engineering, Mike Cobb manages the day-to-day operations of the Engineering Department, including the physical and logical recoveries of rotational media, SSDs, smart devices and flash media. He also oversees the R&amp;D efforts for past, present, and future storage technologies. Mike encourages growth and ensures that each of the departments and their engineers continues to gain knowledge in their field. Each DriveSavers engineer has been trained to ensure the successful and complete recovery of data is their top priority. As Chief Information Security Officer (CISO), Mike oversees cybersecurity at DriveSavers, including maintaining and updating security certifications such as SOC 2 Type II compliance, coordinating company security policy, and employee cybersecurity education. Mike joined DriveSavers in 1994 and has a B.S. degree in Computer Science from the University of California, Riverside.","sameAs":["http:\/\/\/"],"url":"https:\/\/drivesaversdatarecovery.com\/it-it\/author\/mikecobb\/"}]}},"_links":{"self":[{"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/posts\/10099","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/users\/25"}],"replies":[{"embeddable":true,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/comments?post=10099"}],"version-history":[{"count":1,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/posts\/10099\/revisions"}],"predecessor-version":[{"id":83004,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/posts\/10099\/revisions\/83004"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/media\/66435"}],"wp:attachment":[{"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/media?parent=10099"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/categories?post=10099"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/tags?post=10099"},{"taxonomy":"post_series","embeddable":true,"href":"https:\/\/drivesaversdatarecovery.com\/it-it\/wp-json\/wp\/v2\/post_series?post=10099"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}